{"id":4515,"date":"2026-03-12T19:18:57","date_gmt":"2026-03-12T17:18:57","guid":{"rendered":"https:\/\/agentaya.com\/?p=4515"},"modified":"2026-03-13T18:17:06","modified_gmt":"2026-03-13T16:17:06","slug":"descubre-como-manx-whisky-company-usa-la-ia","status":"publish","type":"post","link":"https:\/\/agentaya.com\/es\/descubre-como-manx-whisky-company-usa-la-ia\/","title":{"rendered":"\u00bfC\u00f3mo encaja la IA en la elaboraci\u00f3n tradicional de whisky?"},"content":{"rendered":"\n<p><em>Este art\u00edculo fue publicado originalmente en <\/em><a href=\"https:\/\/manxwhisky.com\/blogs\/whisky-making\/ai-in-whisky-making\" target=\"_blank\" rel=\"noopener\"><em>https:\/\/manxwhisky.com\/<\/em><\/a> <em>por Manx Whisky Company, una peque\u00f1a destiler\u00eda tradicional ubicada en Baldrine, en la Isla de Man. Fundada en 2019 por Magnus Grinneback y Scott Young, se dedica a producir aut\u00e9ntico whisky single malt con materias primas de origen local. Lo publicamos en <a href=\"https:\/\/agentaya.com\/es\/\" data-type=\"page\" data-id=\"6\">AgentAya<\/a> con su autorizaci\u00f3n.<\/em><\/p>\n\n\n<div class=\"wp-block-image wp-duotone-unset-1\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"628\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-4-1024x628.avif\" alt=\"manx whisky company\" class=\"wp-image-4520\" style=\"width:600px\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-4-1024x628.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-4-300x184.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-4-768x471.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-4.avif 1449w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Nuestra forma de hacer whisky es muy tradicional. Recogemos la cebada de Ballavell Farm, y gran parte de lo que sigue le habr\u00eda resultado familiar a un destilador de hace 250 a\u00f1os (puedes leer m\u00e1s sobre nuestro equipamiento y proceso aqu\u00ed).<\/p>\n\n\n\n<p>Entonces, \u00bfc\u00f3mo encaja la inteligencia artificial en todo esto?<\/p>\n\n\n\n<p>De varias maneras, la verdad. Seguimos de cerca los avances en IA y evaluamos constantemente c\u00f3mo puede facilitarnos el trabajo. Veamos algunos ejemplos, de lo m\u00e1s sencillo a lo m\u00e1s avanzado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"_Lo_basico_como_usamos_la_IA_en_las_tareas_del_dia_a_dia\"><\/span>&nbsp;Lo b\u00e1sico: c\u00f3mo usamos la IA en las tareas del d\u00eda a d\u00eda<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1. Redacci\u00f3n de textos: pulir la comunicaci\u00f3n<\/h3>\n\n\n\n<p>No usamos la <a href=\"https:\/\/agentaya.com\/es\/ia-para-redaccion\/\" data-type=\"page\" data-id=\"443\">IA para escribir<\/a> desde cero. Las publicaciones de Instagram, los art\u00edculos del blog (incluido este) y los boletines siempre parten de un borrador que escribimos nosotros.<\/p>\n\n\n\n<p>Lo que s\u00ed hacemos es usar la IA para pulir ese texto inicial. Esto acelera el camino del primer borrador a la versi\u00f3n final. Hemos experimentado con entrenar un GPT para que redacte publicaciones desde cero, pero los resultados no son lo bastante buenos: demasiados clich\u00e9s y demasiado sensacionalismo. Por ahora, preferimos escribir con nuestra propia voz y usar la IA para refinarla, no para sustituirla.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">2. Peque\u00f1as tareas de programaci\u00f3n: mejorar las notificaciones al cliente<\/h3>\n\n\n\n<p>Nuestra web funciona con Shopify, una plataforma que funciona muy bien. Sin embargo, de vez en cuando necesitamos ajustar la l\u00f3gica. Por ejemplo, una reserva para una cata y una compra de botellas requieren correos de confirmaci\u00f3n con informaci\u00f3n muy diferente.<\/p>\n\n\n\n<p>En estos casos, la IA nos ha resultado extremadamente \u00fatil. Aunque tengo algo de experiencia en programaci\u00f3n de mis a\u00f1os de estudiante, hace ya 30 a\u00f1os, estoy completamente perdido con el entorno de scripting de Shopify. La IA nos permite hacer estos cambios por nuestra cuenta en lugar de contratar a un desarrollador.<\/p>\n\n\n\n<p>De cara al futuro, es posible que sustituyamos algunos de los m\u00f3dulos de pago que usamos actualmente (el de verificaci\u00f3n de edad, por ejemplo) por c\u00f3digo propio desarrollado con ayuda de la IA. Estos m\u00f3dulos no son caros, pero merece la pena si podemos ahorrarnos 10 libras al mes y construir algo m\u00e1s adaptado a nuestras necesidades.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">3. Automatizar lo administrativo: simplificar las declaraciones mensuales de la destiler\u00eda<\/h3>\n\n\n\n<p>Dirigir una destiler\u00eda implica presentar declaraciones mensuales de producci\u00f3n y retiradas de almac\u00e9n. Eso significa formularios, que no son precisamente la parte m\u00e1s emocionante del trabajo.<\/p>\n\n\n\n<p>Hemos usado la IA (Claude, en este caso) para escribir un script que rellena autom\u00e1ticamente los formularios a partir de nuestros datos de producci\u00f3n. No es nada revolucionario, pero nos ahorra entre 5 y 10 minutos al mes. Y lo m\u00e1s importante: nos ha demostrado lo f\u00e1cil que es crear peque\u00f1os scripts que automaticen tareas concretas.<\/p>\n\n\n\n<p>C\u00f3mo usamos la IA para desarrollar herramientas propias para la destiler\u00eda.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"742\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-5-1024x742.avif\" alt=\"manx whisky casks\" class=\"wp-image-4521\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-5-1024x742.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-5-300x218.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-5-768x557.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-5-1536x1114.avif 1536w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-5.avif 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_usamos_la_IA_para_crear_herramientas_para_la_destileria\"><\/span>C\u00f3mo usamos la IA para crear herramientas para la destiler\u00eda<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\">1. Crear nuestra propia aplicaci\u00f3n de medici\u00f3n<\/h3>\n\n\n\n<p>En una semana t\u00edpica de destilaci\u00f3n hacemos numerosas mediciones y c\u00e1lculos: temperaturas del agua de maceraci\u00f3n, correcciones de temperatura para las lecturas de alcohol y az\u00facar, c\u00e1lculos de diluci\u00f3n y m\u00e1s.<\/p>\n\n\n\n<p>Existen muchas herramientas en l\u00ednea que resuelven cada una de estas tareas por separado. Sin embargo, rara vez funcionan exactamente como nosotros trabajamos, lo que a menudo implica ir saltando entre sitios web y unir los resultados de forma manual.<\/p>\n\n\n\n<p>Para solucionarlo, hemos desarrollado nuestra propia aplicaci\u00f3n, adaptada a nuestro flujo de trabajo. Contiene todo lo que necesitamos en un solo lugar. Esto simplifica el trabajo en la destiler\u00eda, reduce el tiempo dedicado a verificar cifras y, sobre todo, disminuye el riesgo de errores.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"391\" height=\"686\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-1.avif\" alt=\"\" class=\"wp-image-4517\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-1.avif 391w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-1-171x300.avif 171w\" sizes=\"auto, (max-width: 391px) 100vw, 391px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center\"><em><em>Este es un ejemplo de c\u00f3mo hemos adaptado una calculadora de maceraci\u00f3n est\u00e1ndar a nuestra configuraci\u00f3n particular. Sin entrar en demasiados detalles, tiene en cuenta el agua precalentada y calcula tanto el reposo proteico que siempre realizamos como la temperatura necesaria del agua de infusi\u00f3n.<\/em><\/em><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"391\" height=\"686\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image.avif\" alt=\"\" class=\"wp-image-4516\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image.avif 391w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-171x300.avif 171w\" sizes=\"auto, (max-width: 391px) 100vw, 391px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-text-align-center\"><em><em>Este es otro ejemplo. Se trata de una herramienta est\u00e1ndar de correcci\u00f3n de temperatura del hidr\u00f3metro, pero vinculada directamente a la densidad original del fermentador. No es necesario realizar una correcci\u00f3n de temperatura por separado. Todo se calcula en un mismo lugar, ofreci\u00e9ndonos la lectura de alcohol y la atenuaci\u00f3n sin tener que ir cambiando de pantalla o de herramienta.<\/em><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"751\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-9-1024x751.avif\" alt=\"cask and distillery management \" class=\"wp-image-4525\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-9-1024x751.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-9-300x220.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-9-768x564.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-9-1536x1127.avif 1536w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-9.avif 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">2. Software de gesti\u00f3n de barricas y de la destiler\u00eda<\/h3>\n\n\n\n<p>Hasta hace poco, gestion\u00e1bamos nuestras barricas y el inventario con Excel. Funcionaba, pero era engorroso y llevaba mucho tiempo. Es f\u00e1cil cometer errores, y hacer un seguimiento de qu\u00e9 maceraci\u00f3n fue a parar a qu\u00e9 barrica requiere concentraci\u00f3n total.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"666\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-3-1024x666.avif\" alt=\"\" class=\"wp-image-4519\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-3-1024x666.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-3-300x195.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-3-768x499.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-3.avif 1295w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em><em>Este era un ejemplo de nuestra vista general de barricas en Excel. Adem\u00e1s, cada barrica ten\u00eda su propia hoja de c\u00e1lculo individual. A medida que nuestro inventario crec\u00eda, gestionar todo esto se volvi\u00f3 cada vez m\u00e1s dif\u00edcil.<\/em><\/em><\/p>\n\n\n\n<p>Ahora hemos usado la IA para ayudarnos a desarrollar nuestro propio software de gesti\u00f3n de barricas. Con un clic podemos ver el historial completo de cada barrica, su antig\u00fcedad y los datos de producci\u00f3n asociados. El sistema tambi\u00e9n nos avisa cuando toca tomar muestras o realizar otras acciones programadas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"699\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-10-1024x699.avif\" alt=\"overdue actions\" class=\"wp-image-4530\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-10-1024x699.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-10-300x205.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-10-768x525.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-10.avif 1237w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"699\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-45-1024x699.avif\" alt=\"\" class=\"wp-image-4583\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-45-1024x699.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-45-300x205.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-45-768x525.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-45.avif 1237w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left\"><em>Arriba se puede ver una captura de pantalla que muestra las acciones vencidas y una lista de nuestros lotes activos: un contraste notable con la soluci\u00f3n basada en Excel.<\/em><\/p>\n\n\n\n<p>Actualmente estamos trabajando en integrar los registros de maceraci\u00f3n y destilaci\u00f3n en el sistema. El paso final ser\u00e1 a\u00f1adir scripts que preparen autom\u00e1ticamente nuestras declaraciones mensuales de producci\u00f3n y retirada para Aduanas e Impuestos Especiales.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-11-1024x614.avif\" alt=\"mash log excel\" class=\"wp-image-4531\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-11-1024x614.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-11-300x180.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-11-768x460.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-11.avif 1490w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em><em>Aqu\u00ed se puede ver parte de nuestro antiguo registro de maceraci\u00f3n: muchas entradas manuales y una cantidad considerable de c\u00e1lculos.<\/em><\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"703\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-2-1024x703.avif\" alt=\"\" class=\"wp-image-4518\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-2-1024x703.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-2-300x206.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-2-768x527.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-2.avif 1241w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><em><em>Aqu\u00ed est\u00e1 el nuevo sistema: limpio, estructurado y mucho m\u00e1s f\u00e1cil de navegar. A\u00fan es reciente, pero esperamos que simplifique significativamente el mantenimiento de registros, una parte fundamental de la gesti\u00f3n de una destiler\u00eda.<\/em><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Como_usamos_la_IA_para_investigar_y_disenar\"><\/span>C\u00f3mo usamos la IA para investigar y dise\u00f1ar<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La IA tambi\u00e9n es una excelente asistente de investigaci\u00f3n. Si tenemos curiosidad por algo por ejemplo, c\u00f3mo podr\u00eda afectar al sabor una cebada con alto contenido en prote\u00ednas, la IA puede ofrecernos una introducci\u00f3n estructurada en cuesti\u00f3n de minutos. Eso nos permite ponernos al d\u00eda r\u00e1pidamente antes de decidir si profundizar m\u00e1s.<\/p>\n\n\n\n<p>Tambi\u00e9n resulta \u00fatil a la hora de planificar mejoras f\u00edsicas. Actualmente estamos trabajando en un sistema mejorado de recuperaci\u00f3n de agua caliente del condensador. La inteligencia artificial nos ayud\u00f3 a dise\u00f1ar el sistema de control electr\u00f3nico de la bomba, sugerir componentes, estimar costes e identificar proveedores.<\/p>\n\n\n\n<p>Gran parte de esto podr\u00eda hacerse sin IA, pero llevar\u00eda mucho m\u00e1s tiempo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-8-1024x768.avif\" alt=\"manx whisky tasting\" class=\"wp-image-4524\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-8-1024x768.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-8-300x225.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-8-768x576.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-8-1536x1152.avif 1536w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-8.avif 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Reflexiones_finales\"><\/span>Reflexiones finales<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La IA nos est\u00e1 permitiendo investigar, dise\u00f1ar y construir sistemas que antes habr\u00edan sido demasiado costosos o laboriosos para una destiler\u00eda peque\u00f1a. Las herramientas en s\u00ed son econ\u00f3micas. Usamos tanto ChatGPT como Claude. Cada uno cuesta alrededor de 20 USD al mes por una suscripci\u00f3n Pro.<\/p>\n\n\n\n<p>La inteligencia artificial no va a cambiar la forma en que malteamos, maceramos, destilamos o envejecemos nuestro whisky. Pero como empresa peque\u00f1a, nos resulta un aliado poderoso: uno que reduce el tiempo dedicado a la administraci\u00f3n y aumenta el tiempo que invertimos en lo que realmente importa: hacer whisky y mejorar nuestra producci\u00f3n.<\/p>\n\n\n<style>.kb-image4515_7d7791-e3 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image4515_7d7791-e3\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-6-768x1024.avif\" alt=\"distillery manx whisky\" class=\"kb-img wp-image-4522\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-6-768x1024.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-6-225x300.avif 225w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-6-1152x1536.avif 1152w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/03\/image-6.avif 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure><\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4515_7a1ef1-51, .wp-block-kadence-advancedheading.kt-adv-heading4515_7a1ef1-51[data-kb-block=\"kb-adv-heading4515_7a1ef1-51\"]{font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4515_7a1ef1-51 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4515_7a1ef1-51[data-kb-block=\"kb-adv-heading4515_7a1ef1-51\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4515_7a1ef1-51 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4515_7a1ef1-51[data-kb-block=\"kb-adv-heading4515_7a1ef1-51\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4515_7a1ef1-51 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4515_7a1ef1-51\"><span class=\"ez-toc-section\" id=\"Related_Posts\"><\/span>Related Posts<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n<style>.kb-posts-id-4515_024745-62 .loop-entry{background:transparent;box-shadow:none;}.kb-posts-id-4515_024745-62 .loop-entry > .entry-content-wrap{padding:0px;}.kb-posts-id-4515_024745-62 .loop-entry .post-thumbnail{margin-bottom:1em;}.kb-posts-id-4515_024745-62 .kb-post-list-item{display:grid;}<\/style><ul class=\"wp-block-kadence-posts kb-posts kadence-posts-list kb-posts-id-4515_024745-62 content-wrap grid-cols kb-posts-style-unboxed grid-sm-col-2 grid-lg-col-2 item-image-style-above\"><li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4700 post type-post status-publish format-standard has-post-thumbnail hentry category-case-study\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/agentaya.com\/es\/zero-coding-skills-100-budget-how-one-entrepreneur-vibe-coded-a-complete-ai-photography-platform-from-scratch\/\" aria-label=\"Sin conocimientos de programaci\u00f3n y con $100: as\u00ed construy\u00f3 un emprendedor una plataforma fotogr\u00e1fica de IA completa desde cero\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"255\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-8-768x255.avif\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"Sin conocimientos de programaci\u00f3n y con $100: as\u00ed construy\u00f3 un emprendedor una plataforma fotogr\u00e1fica de IA completa desde cero\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-8-768x255.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-8-300x100.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-8-1024x340.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-8-1536x510.avif 1536w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-8.avif 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-normal\">\n\t\t\t<a href=\"https:\/\/agentaya.com\/es\/case-study\/\" class=\"category-link-case-study\" rel=\"tag\">Case Study<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><span class=\"ez-toc-section\" id=\"Sin_conocimientos_de_programacion_y_con_100_asi_construyo_un_emprendedor_una_plataforma_fotografica_de_IA_completa_desde_cero\"><\/span><a href=\"https:\/\/agentaya.com\/es\/zero-coding-skills-100-budget-how-one-entrepreneur-vibe-coded-a-complete-ai-photography-platform-from-scratch\/\" rel=\"bookmark\">Sin conocimientos de programaci\u00f3n y con $100: as\u00ed construy\u00f3 un emprendedor una plataforma fotogr\u00e1fica de IA completa desde cero<\/a><span class=\"ez-toc-section-end\"><\/span><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"author vcard\"><span class=\"fn n\">AgentAya<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published\" datetime=\"2026-04-21T07:39:39+02:00\">April 21, 2026<\/time><time class=\"updated\" datetime=\"2026-06-27T00:30:17+02:00\">June 27, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/agentaya.com\/es\/zero-coding-skills-100-budget-how-one-entrepreneur-vibe-coded-a-complete-ai-photography-platform-from-scratch\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> Sin conocimientos de programaci\u00f3n y con $100: as\u00ed construy\u00f3 un emprendedor una plataforma fotogr\u00e1fica de IA completa desde cero<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<li class=\"kb-post-list-item\">\n\t<article class=\"entry content-bg loop-entry post-4655 post type-post status-publish format-standard has-post-thumbnail hentry category-case-study\">\n\t\t\t\t<a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" class=\"post-thumbnail kadence-thumbnail-ratio-2-3\" href=\"https:\/\/agentaya.com\/es\/ai-and-charities-why-the-third-sector-is-starting-to-pay-attention\/\" aria-label=\"AI and charities: why the third sector is starting to pay attention\">\n\t\t\t<div class=\"post-thumbnail-inner\">\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"369\" src=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-768x369.avif\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"ai and charities\" srcset=\"https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-768x369.avif 768w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-300x144.avif 300w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-1024x492.avif 1024w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image-1536x737.avif 1536w, https:\/\/agentaya.com\/wp-content\/uploads\/2026\/04\/image.avif 2048w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t<\/div>\n\t\t<\/a><!-- .post-thumbnail -->\n\t\t\t\t<div class=\"entry-content-wrap\">\n\t\t\t<header class=\"entry-header\">\n\t\t<div class=\"entry-taxonomies\">\n\t\t<span class=\"category-links term-links category-style-normal\">\n\t\t\t<a href=\"https:\/\/agentaya.com\/es\/case-study\/\" class=\"category-link-case-study\" rel=\"tag\">Case Study<\/a>\t\t<\/span>\n\t<\/div><!-- .entry-taxonomies -->\n\t<h2 class=\"entry-title\"><span class=\"ez-toc-section\" id=\"AI_and_charities_why_the_third_sector_is_starting_to_pay_attention\"><\/span><a href=\"https:\/\/agentaya.com\/es\/ai-and-charities-why-the-third-sector-is-starting-to-pay-attention\/\" rel=\"bookmark\">AI and charities: why the third sector is starting to pay attention<\/a><span class=\"ez-toc-section-end\"><\/span><\/h2>\t<div class=\"entry-meta entry-meta-divider-dot\">\n\t<span class=\"posted-by\"><span class=\"author vcard\"><span class=\"fn n\">AgentAya<\/span><\/span><\/span>\t\t\t<span class=\"posted-on\">\n\t\t\t\t<time class=\"entry-date published\" datetime=\"2026-04-15T08:31:19+02:00\">April 15, 2026<\/time><time class=\"updated\" datetime=\"2026-04-15T08:32:29+02:00\">April 15, 2026<\/time>\t\t\t<\/span>\n\t\t\t\t<\/div><!-- .entry-meta -->\n\t<\/header><!-- .entry-header -->\n<footer class=\"entry-footer\">\n\t\t\t<div class=\"entry-actions\">\n\t\t\t<p class=\"more-link-wrap\">\n\t\t\t\t<a href=\"https:\/\/agentaya.com\/es\/ai-and-charities-why-the-third-sector-is-starting-to-pay-attention\/\" class=\"post-more-link\">\n\t\t\t\t\tRead More<span class=\"screen-reader-text\"> AI and charities: why the third sector is starting to pay attention<\/span><span class=\"kadence-svg-iconset svg-baseline\"><svg aria-hidden=\"true\" class=\"kadence-svg-icon kadence-arrow-right-alt-svg\" fill=\"currentColor\" version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"27\" height=\"28\" viewBox=\"0 0 27 28\"><title>Continue<\/title><path d=\"M27 13.953c0 0.141-0.063 0.281-0.156 0.375l-6 5.531c-0.156 0.141-0.359 0.172-0.547 0.094-0.172-0.078-0.297-0.25-0.297-0.453v-3.5h-19.5c-0.281 0-0.5-0.219-0.5-0.5v-3c0-0.281 0.219-0.5 0.5-0.5h19.5v-3.5c0-0.203 0.109-0.375 0.297-0.453s0.391-0.047 0.547 0.078l6 5.469c0.094 0.094 0.156 0.219 0.156 0.359v0z\"><\/path>\n\t\t\t<\/svg><\/span>\t\t\t\t<\/a>\n\t\t\t<\/p>\n\t\t<\/div><!-- .entry-actions -->\n\t\t<\/footer><!-- .entry-footer -->\t\t<\/div>\n\t<\/article>\n<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Este art\u00edculo fue publicado originalmente en https:\/\/manxwhisky.com\/ por Manx Whisky Company, una peque\u00f1a destiler\u00eda tradicional ubicada en Baldrine, en la&#8230;<\/p>\n","protected":false},"author":2,"featured_media":4523,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[79],"tags":[],"class_list":["post-4515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-case-study"],"acf":[],"_links":{"self":[{"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/posts\/4515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/comments?post=4515"}],"version-history":[{"count":12,"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/posts\/4515\/revisions"}],"predecessor-version":[{"id":4589,"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/posts\/4515\/revisions\/4589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/media\/4523"}],"wp:attachment":[{"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/media?parent=4515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/categories?post=4515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agentaya.com\/es\/wp-json\/wp\/v2\/tags?post=4515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}